{"id":11024,"date":"2025-10-25T18:35:37","date_gmt":"2025-10-25T18:35:37","guid":{"rendered":"https:\/\/livrariasolmar.pt\/?post_type=product&#038;p=11024"},"modified":"2026-01-18T17:22:43","modified_gmt":"2026-01-18T17:22:43","slug":"a-ultima-amante","status":"publish","type":"product","link":"https:\/\/livrariasolmar.pt\/en\/produto\/a-ultima-amante\/","title":{"rendered":"A \u00daltima Amante"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Neste extraordin\u00e1rio livro de Can Xue &#8211; a maior voz da literatura chinesa atual -, h\u00e1 um conjunto completo de maridos, esposas e amantes. \u00c9 uma magistral hist\u00f3ria sobre amor e identidade. Entrela\u00e7adas em rela\u00e7\u00f5es complicadas, muitas vezes tortuosas, estas personagens envolvem-se nas fantasias umas das outras, mantendo conversas que s\u00e3o\u00a0<i>eternos jogos de adivinha\u00e7\u00e3o<\/i>.<\/p>\n<p>As suas viagens revelam os reinos mais profundos do desejo humano. Em bares decadentes e ruas sinuosas da cidade, em desertos ou montanhas tingidas de neve, Can Xue cria um mundo extremo onde cada personagem tenta afastar a morte e o passado.<\/p>\n<p>Quem \u00e9 a \u00faltima amante? O romance est\u00e1 repleto de personagens fabulosas. Entre elas est\u00e3o Joe, vendedor de uma empresa de vestu\u00e1rio num pa\u00eds ocidental desconhecido, e a sua mulher, Maria, que realiza experi\u00eancias m\u00edsticas com os gatos e as roseiras da casa.<\/p>\n<p>Reagan, cliente de Joe, tem um caso com Ida, uma funcion\u00e1ria da sua planta\u00e7\u00e3o de borracha, enquanto Vincent, dono de uma loja de roupa, foge da mulher em busca de uma mulher de negro que desaparece sucessivamente. No final do romance, acompanhamos estas personagens numa longa viagem, uma busca ing\u00e9nua, desamparada e abandonada pelo amor, porque h\u00e1 certas coisas que n\u00e3o podem ser impedidas \u2014 nem evitadas.<\/p>\n","protected":false},"author":2,"featured_media":11025,"template":"","meta":[],"product_cat":[153],"product_tag":[],"cat_produtos":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A \u00daltima Amante - Livraria Solmar - Livraria online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livrariasolmar.pt\/en\/produto\/a-ultima-amante\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A \u00daltima Amante - Livraria Solmar - Livraria online\" \/>\n<meta property=\"og:description\" content=\"Neste extraordin\u00e1rio livro de Can Xue - a maior voz da literatura chinesa atual -, h\u00e1 um conjunto completo de maridos, esposas e amantes. \u00c9 uma magistral hist\u00f3ria sobre amor e identidade. Entrela\u00e7adas em rela\u00e7\u00f5es complicadas, muitas vezes tortuosas, estas personagens envolvem-se nas fantasias umas das outras, mantendo conversas que s\u00e3o\u00a0eternos jogos de adivinha\u00e7\u00e3o.  As suas viagens revelam os reinos mais profundos do desejo humano. Em bares decadentes e ruas sinuosas da cidade, em desertos ou montanhas tingidas de neve, Can Xue cria um mundo extremo onde cada personagem tenta afastar a morte e o passado.  Quem \u00e9 a \u00faltima amante? O romance est\u00e1 repleto de personagens fabulosas. Entre elas est\u00e3o Joe, vendedor de uma empresa de vestu\u00e1rio num pa\u00eds ocidental desconhecido, e a sua mulher, Maria, que realiza experi\u00eancias m\u00edsticas com os gatos e as roseiras da casa.  Reagan, cliente de Joe, tem um caso com Ida, uma funcion\u00e1ria da sua planta\u00e7\u00e3o de borracha, enquanto Vincent, dono de uma loja de roupa, foge da mulher em busca de uma mulher de negro que desaparece sucessivamente. No final do romance, acompanhamos estas personagens numa longa viagem, uma busca ing\u00e9nua, desamparada e abandonada pelo amor, porque h\u00e1 certas coisas que n\u00e3o podem ser impedidas \u2014 nem evitadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/\" \/>\n<meta property=\"og:site_name\" content=\"Livraria Solmar - Livraria online\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-18T17:22:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/livrariasolmar.pt\/wp-content\/uploads\/2025\/10\/1540-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"340\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/livrariasolmar.pt\/#website\",\"url\":\"https:\/\/livrariasolmar.pt\/\",\"name\":\"Livraria Solmar - Livraria online\",\"description\":\"Com\\u00e9rcio Livros E Objetos De Arte, Lda - Ponta Delgada, A\\u00e7ores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/livrariasolmar.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/livrariasolmar.pt\/wp-content\/uploads\/2025\/10\/1540-1-2.jpg\",\"contentUrl\":\"https:\/\/livrariasolmar.pt\/wp-content\/uploads\/2025\/10\/1540-1-2.jpg\",\"width\":340,\"height\":340},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/#webpage\",\"url\":\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/\",\"name\":\"A \\u00daltima Amante - Livraria Solmar - Livraria online\",\"isPartOf\":{\"@id\":\"https:\/\/livrariasolmar.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/#primaryimage\"},\"datePublished\":\"2025-10-25T18:35:37+00:00\",\"dateModified\":\"2026-01-18T17:22:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/livrariasolmar.pt\/produto\/a-ultima-amante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/livrariasolmar.pt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/livrariasolmar.pt\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A \\u00daltima Amante\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/product\/11024"}],"collection":[{"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/media\/11025"}],"wp:attachment":[{"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/media?parent=11024"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/product_cat?post=11024"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/product_tag?post=11024"},{"taxonomy":"cat_produtos","embeddable":true,"href":"https:\/\/livrariasolmar.pt\/en\/wp-json\/wp\/v2\/cat_produtos?post=11024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}